{"id":945,"count":1,"description":"(Otto Viktor Fr\u00f6licher, Otto Fr\u00f6hlicher, Otto Froelicher)\r\n\r\n<strong>Otto Fr\u00f6licher fue un destacado pintor paisajista suizo y, junto con Johann Adolf St\u00e4bli, uno de los principales representantes del \u00abPaysage intime\u00bb en la Suiza alemana.<\/strong> \r\n\r\nOtto Fr\u00f6licher fue miembro de la sociedad art\u00edstica Allotria, una rama de la cooperativa de artistas de M\u00fanich a la que pertenec\u00edan los artistas que no participaban en la exposici\u00f3n de arte del Glaspalast. Por otra parte, Fr\u00f6licher fue miembro del jurado de dicha exposici\u00f3n en varias ocasiones. Adem\u00e1s, fue presidente de la Asociaci\u00f3n Suiza de Apoyo en M\u00fanich.\r\n\r\n<h2>Obras de Otto Fr\u00f6licher<\/h2>\r\nA continuaci\u00f3n encontrar\u00e1 obras de Otto Fr\u00f6licher:\r\n","link":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/","name":"Otto FR\u00d6LICHER (* 1840, \u2020 1890)","slug":"otto-froelicher","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen<\/title>\n<meta name=\"description\" content=\"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen\" \/>\n<meta property=\"og:description\" content=\"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBERT Z\u00dcBLIN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/otto-froelicher\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/otto-froelicher\\\/\",\"name\":\"Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\"},\"description\":\"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/otto-froelicher\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/otto-froelicher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otto FR\u00d6LICHER (* 1840, \u2020 1890)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"name\":\"ROBERT Z\u00dcBLIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\",\"name\":\"ROBERT Z\u00dcBLIN\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"width\":440,\"height\":120,\"caption\":\"ROBERT Z\u00dcBLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen","description":"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/","og_locale":"es_ES","og_type":"article","og_title":"Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen","og_description":"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.","og_url":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/","og_site_name":"ROBERT Z\u00dcBLIN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/","url":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/","name":"Otto FR\u00d6LICHER (* 1840, \u2020 1890) - Kunst-Bilder kaufen","isPartOf":{"@id":"https:\/\/www.robertzueblin.com\/es\/#website"},"description":"Der Maler Otto Fr\u00f6licher war ein bedeutender Schweizer Landschaftsmaler und einer der f\u00fchrenden Vertreter des Paysage intime in der Deutschschweiz.","breadcrumb":{"@id":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.robertzueblin.com\/es\/otto-froelicher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.robertzueblin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Otto FR\u00d6LICHER (* 1840, \u2020 1890)"}]},{"@type":"WebSite","@id":"https:\/\/www.robertzueblin.com\/es\/#website","url":"https:\/\/www.robertzueblin.com\/es\/","name":"ROBERT Z\u00dcBLIN","description":"","publisher":{"@id":"https:\/\/www.robertzueblin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robertzueblin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.robertzueblin.com\/es\/#organization","name":"ROBERT Z\u00dcBLIN","url":"https:\/\/www.robertzueblin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","width":440,"height":120,"caption":"ROBERT Z\u00dcBLIN"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat\/945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product?product_cat=945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}