{"id":190,"count":4,"description":"<table cellpadding=\"1\">\r\n\t<tbody>\r\n\t\t<tr>\r\n\t\t\t<td style=\"padding-left: 0em!important\">\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1885<\/span> <br> nace en Speldorf (Bajo Rin), Alemania<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1897-1911<\/span> <br>trabaja en una f\u00e1brica de ladrillos<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1910<\/span> <br> funda la \"Kunstt\u00f6pferei Gebr\u00fcder Hehl\" (Alfarer\u00eda art\u00edstica Hermanos Hehl) en Rheinhausen<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1912-1929<\/span> <br> se hacen cargo de una alfarer\u00eda en Krefeld (desde 1913 en solitario)<\/p>\r\n\t\t\t<\/td>\r\n\t\t\t<td style=\"padding-left: 0.3em!important\">\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1920<\/span> <br>nuevo comienzo tras el regreso despu\u00e9s de ser prisionero de guerra<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1929-1953<\/span> <br>taller y casa en Xanten, proporcionados por el distrito de Moers<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1945<\/span> <br>destrucci\u00f3n parcial de casa, taller y obras por bombardeo<\/p>\r\n\r\n\t\t\t<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">1953<\/span> <br> muere en Xanten, Alemania<\/p>\r\n\t\t\t<\/td>\r\n\t\t<\/tr>\r\n\t<\/tbody>\r\n<\/table>\r\n\r\n<em>Fuente:<\/em>  \r\n- Verein Stadtkultur Xanten e.V., Regionalmuseum Xanten (editor): Josef Hehl, 1885 hasta 1953, Xanten 2003, pp. 136-138.<\/p>\r\n<div>\u00a0<\/div>","link":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/","name":"Josef HEHL (* 1885, \u2020 1953)","slug":"josef-hehl","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen<\/title>\n<meta name=\"description\" content=\"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen\" \/>\n<meta property=\"og:description\" content=\"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBERT Z\u00dcBLIN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/josef-hehl\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/josef-hehl\\\/\",\"name\":\"Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\"},\"description\":\"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/josef-hehl\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/josef-hehl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Josef HEHL (* 1885, \u2020 1953)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"name\":\"ROBERT Z\u00dcBLIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\",\"name\":\"ROBERT Z\u00dcBLIN\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"width\":440,\"height\":120,\"caption\":\"ROBERT Z\u00dcBLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen","description":"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/","og_locale":"es_ES","og_type":"article","og_title":"Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen","og_description":"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.","og_url":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/","og_site_name":"ROBERT Z\u00dcBLIN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/","url":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/","name":"Josef HEHL (* 1885, \u2020 1953) - Keramik kaufen","isPartOf":{"@id":"https:\/\/www.robertzueblin.com\/es\/#website"},"description":"Der Studiokeramiker Josef Hehl geh\u00f6rt zu den gr\u00f6\u00dften deutschen Keramikern insbesondere zwischen den Kriegen und sticht mit Formen und Glasuren heraus.","breadcrumb":{"@id":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.robertzueblin.com\/es\/josef-hehl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.robertzueblin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Josef HEHL (* 1885, \u2020 1953)"}]},{"@type":"WebSite","@id":"https:\/\/www.robertzueblin.com\/es\/#website","url":"https:\/\/www.robertzueblin.com\/es\/","name":"ROBERT Z\u00dcBLIN","description":"","publisher":{"@id":"https:\/\/www.robertzueblin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robertzueblin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.robertzueblin.com\/es\/#organization","name":"ROBERT Z\u00dcBLIN","url":"https:\/\/www.robertzueblin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","width":440,"height":120,"caption":"ROBERT Z\u00dcBLIN"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/"}}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product?product_cat=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}