{"id":43267,"date":"2025-02-02T21:15:49","date_gmt":"2025-02-04T11:20:58","guid":{"rendered":"https:\/\/www.robertzueblin.com\/?post_type=product&#038;p=43267"},"modified":"2025-05-05T05:25:48","modified_gmt":"2025-05-05T03:25:48","slug":"louis-curtat-1869-%e2%80%a0-1944-alto-valle-en-los-alpes-acuarela","status":"publish","type":"product","link":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/","title":{"rendered":"Louis CURTAT (* 1869, \u2020 1944) &#8211; Alto valle en los Alpes &#8211; Acuarela"},"content":{"rendered":"<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Tipo:<\/span> <a href=\"https:\/\/www.robertzueblin.com\/es\/tipo\/pintura\/\">cuadros de arte<\/a><\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Pintor:<\/span> <a href=\"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/\">Louis CURTAT<\/a> (* 1869, \u2020 1944)<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Objeto:<\/span> acuarela<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Material:<\/span> acuarela sobre papel<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Dimensiones:<\/span> alto: 9,3 cm, anchura: 14 cm<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Periodo de realizaci\u00f3n:<\/span> finales del siglo XIX\/primera mitad del siglo XX<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Estado:<\/span> bueno<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Firma:<\/span> LC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tipo: cuadros de arte Pintor: Louis CURTAT (* 1869, \u2020 1944) Objeto: acuarela Material: acuarela sobre papel Dimensiones: alto: 9,3 cm, anchura: 14 cm Periodo de realizaci\u00f3n: finales del siglo XIX\/primera mitad del siglo XX Estado: bueno Firma: LC<\/p>\n","protected":false},"featured_media":43270,"template":"","meta":[],"product_brand":[],"product_cat":[778,741],"product_tag":[],"class_list":["post-43267","product","type-product","status-publish","has-post-thumbnail","product_cat-pintura","product_cat-louis-curtat","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela<\/title>\n<meta name=\"description\" content=\"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\/primera mitad del siglo XX).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela\" \/>\n<meta property=\"og:description\" content=\"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\/primera mitad del siglo XX).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBERT Z\u00dcBLIN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T03:25:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/\",\"name\":\"Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg\",\"datePublished\":\"2025-02-04T11:20:58+00:00\",\"dateModified\":\"2025-05-05T03:25:48+00:00\",\"description\":\"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\\\/primera mitad del siglo XX).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg\",\"width\":1200,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/louis-curtat\\\/alto-valle-en-los-alpes-acuarela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galer\u00eda de arte online (tienda online)\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/galeria-de-arte-online\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louis CURTAT (* 1869, \u2020 1944) &#8211; Alto valle en los Alpes &#8211; Acuarela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"name\":\"ROBERT Z\u00dcBLIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\",\"name\":\"ROBERT Z\u00dcBLIN\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"width\":440,\"height\":120,\"caption\":\"ROBERT Z\u00dcBLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela","description":"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\/primera mitad del siglo XX).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/","og_locale":"es_ES","og_type":"article","og_title":"Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela","og_description":"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\/primera mitad del siglo XX).","og_url":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/","og_site_name":"ROBERT Z\u00dcBLIN","article_modified_time":"2025-05-05T03:25:48+00:00","og_image":[{"width":1200,"height":816,"url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/","url":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/","name":"Louis CURTAT (* 1869, \u2020 1944) - Alto valle en los Alpes - Acuarela","isPartOf":{"@id":"https:\/\/www.robertzueblin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/#primaryimage"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg","datePublished":"2025-02-04T11:20:58+00:00","dateModified":"2025-05-05T03:25:48+00:00","description":"Acuarela del pintor suizo Louis Curtat que representa un alto valle de los Alpes (finales del siglo XIX\/primera mitad del siglo XX).","breadcrumb":{"@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/#primaryimage","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/louis-curtat-acuarela-alto-valle-alpes-foto-titulo.jpg","width":1200,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/www.robertzueblin.com\/es\/louis-curtat\/alto-valle-en-los-alpes-acuarela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.robertzueblin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Galer\u00eda de arte online (tienda online)","item":"https:\/\/www.robertzueblin.com\/es\/galeria-de-arte-online\/"},{"@type":"ListItem","position":3,"name":"Louis CURTAT (* 1869, \u2020 1944) &#8211; Alto valle en los Alpes &#8211; Acuarela"}]},{"@type":"WebSite","@id":"https:\/\/www.robertzueblin.com\/es\/#website","url":"https:\/\/www.robertzueblin.com\/es\/","name":"ROBERT Z\u00dcBLIN","description":"","publisher":{"@id":"https:\/\/www.robertzueblin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robertzueblin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.robertzueblin.com\/es\/#organization","name":"ROBERT Z\u00dcBLIN","url":"https:\/\/www.robertzueblin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","width":440,"height":120,"caption":"ROBERT Z\u00dcBLIN"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/"}}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product\/43267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/media\/43270"}],"wp:attachment":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/media?parent=43267"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_brand?post=43267"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat?post=43267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_tag?post=43267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}