{"id":24684,"date":"2022-04-11T09:04:54","date_gmt":"2022-04-11T07:06:07","guid":{"rendered":"https:\/\/www.robertzueblin.com\/?post_type=product&#038;p=24684"},"modified":"2022-12-15T15:42:21","modified_gmt":"2022-12-15T14:42:21","slug":"karl-juettner-1921-%e2%80%a0-2006-jarron-brutalista-de-color-turquesa","status":"publish","type":"product","link":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/","title":{"rendered":"Karl J\u00dcTTNER (* 1921, \u2020 2006) &#8211; Jarr\u00f3n brutalista en color turquesa &#8211; cer\u00e1mica de taller"},"content":{"rendered":"<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Tipo:<\/span> <a href=\"https:\/\/www.robertzueblin.com\/es\/tipo\/ceramica-artistica-ceramica-artesanal-ceramica-de-taller\/\">cer\u00e1mica de taller<\/a><\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Dise\u00f1o:<\/span> Karl J\u00fcttner (* 1921, \u2020 2006)<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Ejecuci\u00f3n:<\/span> taller de Karl J\u00fcttner<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Objeto:<\/span> jarr\u00f3n<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Dimensiones:<\/span> altura: 18 cm, anchura: 10,5 cm<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Cuerpo:<\/span> marr\u00f3n<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Superficie:<\/span> turquesa, gris<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Per\u00edodo de producci\u00f3n:<\/span> probablemente la d\u00e9cada de 1970<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Estado:<\/span> sin da\u00f1os<\/p>\n<p><span style=\"font-family: AkkoPro-BoldCondensed!important\">Firma\/ marca:<\/span> Jue<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tipo: cer\u00e1mica de taller Dise\u00f1o: Karl J\u00fcttner (* 1921, \u2020 2006) Ejecuci\u00f3n: taller de Karl J\u00fcttner Objeto: jarr\u00f3n Dimensiones: altura: 18 cm, anchura: 10,5 cm Cuerpo: marr\u00f3n Superficie: turquesa, gris Per\u00edodo de producci\u00f3n: probablemente la d\u00e9cada de 1970 Estado: sin da\u00f1os Firma\/ marca: Jue<\/p>\n","protected":false},"featured_media":24682,"template":"","meta":[],"product_brand":[],"product_cat":[191],"product_tag":[],"class_list":["post-24684","product","type-product","status-publish","has-post-thumbnail","product_cat-karl-juettner","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller<\/title>\n<meta name=\"description\" content=\"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller\" \/>\n<meta property=\"og:description\" content=\"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBERT Z\u00dcBLIN\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T14:42:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/\",\"name\":\"Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg\",\"datePublished\":\"2022-04-11T07:06:07+00:00\",\"dateModified\":\"2022-12-15T14:42:21+00:00\",\"description\":\"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/karl-juettner\\\/jarron-brutalista-color-turquesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galer\u00eda de arte online (tienda online)\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/galeria-de-arte-online\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Karl J\u00dcTTNER (* 1921, \u2020 2006) &#8211; Jarr\u00f3n brutalista en color turquesa &#8211; cer\u00e1mica de taller\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"name\":\"ROBERT Z\u00dcBLIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#organization\",\"name\":\"ROBERT Z\u00dcBLIN\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"width\":440,\"height\":120,\"caption\":\"ROBERT Z\u00dcBLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller","description":"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/","og_locale":"es_ES","og_type":"article","og_title":"Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller","og_description":"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.","og_url":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/","og_site_name":"ROBERT Z\u00dcBLIN","article_modified_time":"2022-12-15T14:42:21+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/","url":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/","name":"Karl J\u00dcTTNER - Jarr\u00f3n brutalista - cer\u00e1mica de taller","isPartOf":{"@id":"https:\/\/www.robertzueblin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/#primaryimage"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg","datePublished":"2022-04-11T07:06:07+00:00","dateModified":"2022-12-15T14:42:21+00:00","description":"Jarr\u00f3n de cer\u00e1mica brutalista, probablemente de los a\u00f1os 70, del ceramista de la RDA del grupo de artistas de Saalfeld Karl J\u00fcttner.","breadcrumb":{"@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/#primaryimage","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/karl-juettner-ceramica-taller-jarron-brutalista-turquesa-foto-titulo.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.robertzueblin.com\/es\/karl-juettner\/jarron-brutalista-color-turquesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.robertzueblin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Galer\u00eda de arte online (tienda online)","item":"https:\/\/www.robertzueblin.com\/es\/galeria-de-arte-online\/"},{"@type":"ListItem","position":3,"name":"Karl J\u00dcTTNER (* 1921, \u2020 2006) &#8211; Jarr\u00f3n brutalista en color turquesa &#8211; cer\u00e1mica de taller"}]},{"@type":"WebSite","@id":"https:\/\/www.robertzueblin.com\/es\/#website","url":"https:\/\/www.robertzueblin.com\/es\/","name":"ROBERT Z\u00dcBLIN","description":"","publisher":{"@id":"https:\/\/www.robertzueblin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robertzueblin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.robertzueblin.com\/es\/#organization","name":"ROBERT Z\u00dcBLIN","url":"https:\/\/www.robertzueblin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","width":440,"height":120,"caption":"ROBERT Z\u00dcBLIN"},"image":{"@id":"https:\/\/www.robertzueblin.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product\/24684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/media\/24682"}],"wp:attachment":[{"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/media?parent=24684"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_brand?post=24684"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_cat?post=24684"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.robertzueblin.com\/es\/wp-json\/wp\/v2\/product_tag?post=24684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}