{"id":955,"count":1,"description":"","link":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/","name":"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)","slug":"william-williams-plymouth","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBERT Z\u00dcBLIN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/william-williams-plymouth\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/william-williams-plymouth\\\/\",\"name\":\"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/william-williams-plymouth\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/william-williams-plymouth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/\",\"name\":\"ROBERT Z\u00dcBLIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#organization\",\"name\":\"ROBERT Z\u00dcBLIN\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robertzueblin.com\\\/wp-content\\\/uploads\\\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg\",\"width\":440,\"height\":120,\"caption\":\"ROBERT Z\u00dcBLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robertzueblin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/","og_locale":"en_US","og_type":"article","og_title":"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)","og_url":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/","og_site_name":"ROBERT Z\u00dcBLIN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/","url":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/","name":"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)","isPartOf":{"@id":"https:\/\/www.robertzueblin.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.robertzueblin.com\/en\/william-williams-plymouth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.robertzueblin.com\/en\/"},{"@type":"ListItem","position":2,"name":"William WILLIAMS OF PLYMOUTH (* 1808, \u2020 1895)"}]},{"@type":"WebSite","@id":"https:\/\/www.robertzueblin.com\/en\/#website","url":"https:\/\/www.robertzueblin.com\/en\/","name":"ROBERT Z\u00dcBLIN","description":"","publisher":{"@id":"https:\/\/www.robertzueblin.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robertzueblin.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.robertzueblin.com\/en\/#organization","name":"ROBERT Z\u00dcBLIN","url":"https:\/\/www.robertzueblin.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.robertzueblin.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","contentUrl":"https:\/\/www.robertzueblin.com\/wp-content\/uploads\/cropped-logo-robert-zueblin-art-dealer-zurich.jpg","width":440,"height":120,"caption":"ROBERT Z\u00dcBLIN"},"image":{"@id":"https:\/\/www.robertzueblin.com\/en\/#\/schema\/logo\/image\/"}}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.robertzueblin.com\/en\/wp-json\/wp\/v2\/product_cat\/955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robertzueblin.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.robertzueblin.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.robertzueblin.com\/en\/wp-json\/wp\/v2\/product?product_cat=955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}